{"id":15953,"date":"2022-10-03T15:53:48","date_gmt":"2022-10-03T13:53:48","guid":{"rendered":"https:\/\/www.aics.gov.it\/oltremare\/?p=15953"},"modified":"2022-10-06T18:01:50","modified_gmt":"2022-10-06T16:01:50","slug":"il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc","status":"publish","type":"post","link":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/","title":{"rendered":"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc)"},"content":{"rendered":"<p><em>Durante la conferenza Mare Climaticum Nostrum, il climatologo del Centro Euro-Mediterraneo sui Cambiamenti climatici ha presentato a Oltremare un quadro completo e accurato di una regione particolarmente esposta. Riscaldamento dei mari, siccit\u00e0, impatti sulla salute e sulla crescita economica i temi di questo colloquio<br \/>\n<\/em><\/p>\n<p><!--more-->Dal 5 all&#8217;8 ottobre si \u00e8 tenuto a Firenze, presso la Fortezza da Basso, <a href=\"https:\/\/conferenzaclimamediterraneo.it\/it\/il-programma\" target=\"_blank\" rel=\"noopener\"><strong>Mare Climaticum Nostrum<\/strong><\/a>, <strong>la prima conferenza sugli impatti del cambiamento climatico nell\u2019area del Mediterraneo<\/strong>. Una discussione autorevole basata sui pi\u00f9 aggiornati studi e le ricerche pi\u00f9 avanzate, tesa ad identificare e prevenire gli effetti prodotti in atmosfera, sulle acque, al suolo, in agricoltura, nelle aree urbane, sulle infrastrutture, sulla salute umana e negli ecosistemi ambientali. Oltremare ha intervistato <strong>Antonio Navarra<\/strong>, direttore del<a href=\"https:\/\/www.cmcc.it\/it\/chi-siamo\/cmcc-foundation\" target=\"_blank\" rel=\"noopener\"><strong> Centro Euro-Mediterraneo sui i Cambiamenti Climatici (Cmcc)<\/strong><\/a> di Lecce e <em>main discussant<\/em> dell\u2019evento per identificare la gamma degli impatti previsti \u2013 desertificazione, siccit\u00e0, dissesto idrogeologico e alluvioni, innalzamento dei livelli del mare e cuneo salino, disponibilit\u00e0 qualit\u00e0 e utilizzi dell\u2019acqua in una regione che si \u00e8 riscaldata e continuer\u00e0 a riscaldarsi maggiormente della media globale.<\/p>\n<p><strong>Navarra, come possiamo collocare il Mediterraneo nella classifica delle aree pi\u00f9 vulnerabili a causa del cambiamento climatico?<\/strong><\/p>\n<p>Il Mediterraneo <strong>\u00e8 una delle aree pi\u00f9 vulnerabili<\/strong>, tant&#8217;\u00e8 vero che \u00e8 stata classificata come <em>hotspot<\/em> dal\u2019<a href=\"https:\/\/www.ipcc.ch\/\" target=\"_blank\" rel=\"noopener\">Ipcc<\/a>, il panel intergovernativo sui cambiamenti climatici. \u00c8 il motivo per cui \u00e8 pi\u00f9 vulnerabile al cambiamento climatico e che si trova al confine tra le aree subtropicali e le medie latitudini. Dunque ogni piccola variazione di questi confini ha degli effetti sproporzionati sull&#8217;area.<\/p>\n<p><strong>Qual \u00e8 in sintesi estrema l\u2019effetto del <em>climate change<\/em> nel Mediterraneo?<\/strong><\/p>\n<p>L&#8217;effetto principale \u00e8 quello di<strong> aumentare le temperature e diminuire le precipitazioni<\/strong>, con conseguenze che sono via via pi\u00f9 importanti man mano che si va da nord verso sud. Questo \u00e8 dovuto a tutta una serie di fattori. Principalmente riguardano la riorganizzazione della circolazione atmosferica generale del pianeta a causa dell&#8217;aumento dei gas serra, che scatenano una serie di eventi correlati che alterano le medie di fenomeni come piovosit\u00e0 o temperature. \u00c8 chiaro che spostando la media, che gi\u00e0 influisce su una naturale variabilit\u00e0 del clima, si spostano pure gli estremi di questa variabilit\u00e0. Dunque, il risultato netto \u00e8 un aumento di frequenza degli eventi pi\u00f9 estremi nella distribuzione atmosferica. Quindi <strong>quello ha una probabilit\u00e0 di accadere una volta ogni di cent&#8217;anni, nel giro di qualche decade pu\u00f2 accadere ogni cinque anni<\/strong>.<\/p>\n<p>C\u2019\u00e8 poi il problema dell\u2019<strong>aumento del livello del mare<\/strong> anche se le stime sono caratterizzate da un\u2019altissima variabilit\u00e0. Qui \u00e8 veramente necessario fare delle analisi pi\u00f9 precise, perch\u00e9 ci sono zone dove si pu\u00f2 alzare di molto, zone dove pu\u00f2 addirittura scendere.<\/p>\n<p>In questo caso i fattori sono l\u2019aumento di temperatura e lo scioglimenti dei ghiacciai e dele calotte. Solo la Groenlandia sta contribuendo all\u2019aumento dei livelli di un millimetro ogni anno. Nel Mediterraneo l\u2019innalzamento si distribuisce dappertutto. Il livello del mare per\u00f2 non \u00e8 solo una funzione di quanta acqua ci mettiamo dentro, ma dipende anche dalla circolazione oceanica stessa. Questo fa s\u00ec che ci possono essere delle configurazioni piuttosto complesse, che possono amplificare il valore medio in certe situazioni e deprimere in altre.<\/p>\n<p><strong>Serve quindi avere informazioni sempre pi\u00f9 dettagliate?<\/strong><\/p>\n<p>Serve poter generare delle informazioni che siano poi utilizzabili dalla politica per mitigare il rischio. \u00c8 necessario ottenere informazioni pi\u00f9 localizzate, attraverso l&#8217;uso di modelli numerici locali ad alta risoluzione, ad alta accuratezza spaziale.<\/p>\n<p><strong>In particolar modo sulla gestione idrica, visto le riduzioni di piovosit\u00e0<\/strong><\/p>\n<p>\u00c8 chiaro che con le temperature in crescita e la riduzione della piovosit\u00e0 <strong>la risorsa idrica \u00e8 sotto pressione in tutto il bacino<\/strong> e quindi i settori che usufruiscono di pi\u00f9 della risorsa sono quelli pi\u00f9 impattanti: come l&#8217;agricoltura, ma anche il turismo, un&#8217;attivit\u00e0 ad alta domanda idrica.<\/p>\n<p><strong>Nei paesi di entrambe le sponde del Mediterraneo servono misure urgenti. <\/strong><\/p>\n<p>Bisogna pensare di adattarsi cambiando colture, adottando piante pi\u00f9 idonee al clima, come l\u2019introduzione degli avocado. Il vero problema qui \u00e8 l&#8217;accettabilit\u00e0 sociale di queste misure. Non \u00e8 facile cambiare tradizioni e forme mentali che sono stabilite in un lungo periodo. Anche se poi davanti all\u2019evidenza gli agricoltori saranno costretti a cambiare il modo di coltivare e quello che coltivano.<\/p>\n<p><strong>Il potenziale di adattamento \u00e8 importante per mitigare il rischio?<\/strong><\/p>\n<p>Assolutamente. \u00c8 chiaro che lo stesso aumento di temperatura in una regione con le risorse umane, finanziarie e tecnologiche per intervenire sull\u2019adattamento crea un rischio climatico inferiore. Invece, in una regione dove tali risorse sono scarse il rischio \u00e8 maggiore.<\/p>\n<p>Il Cmcc ha sviluppato degli indici del rischio che considerano sia i <em>driver<\/em> climatici sia la capacit\u00e0 adattativa, ovvero la capacit\u00e0 che una comunit\u00e0 o di un settore di reagire e mettere in campo misure per limitare gli effetti pi\u00f9 nocivi. Non solo: \u00e8 chiaro che in situazioni sociali complesse e delicate il cambiamento climatico rischia di essere un fattore moltiplicativo delle tensioni e dei problemi.<\/p>\n<p><strong>Le tempeste nel Mediterraneo, ribattezzate in inglese <em>medicane<\/em>, che tipo di occorrenza e di impatto avranno nei prossimi anni? <\/strong><\/p>\n<p>Si tratta di eventi per ora piuttosto rari. Come cambier\u00e0 la frequenza a causa del cambiamento climatico? Non lo sappiamo perch\u00e9 si tratta di fenomeni con una scala molto piccola, non sono veri cicloni tropicali che sono molto pi\u00f9 grandi. Rientrano in una classe di modelli che ancora non abbiamo. I medicane sono fenomeni sinottici, cio\u00e8 entrano nel raggio di azione delle previsioni meteorologiche che normalmente si fanno, quindi sono perfettamente prevedibili. Serve un sistema efficace di allerta e monitoraggio in tutta la regione.<\/p>\n<p><strong>Come pu\u00f2 la cooperazione scegliere quali azioni di adattamento sostenere nei paesi pi\u00f9 vulnerabili?<\/strong><\/p>\n<p>C&#8217;\u00e8 una vastissima letteratura su questi problemi e tanto lavoro di analisi, anche localizzato. Il problema \u00e8 trovare la combinazione politica. Se parliamo di cooperazione bisogna mettere assieme i Paesi donatori con i Paesi che ricevono e realizzare interventi efficaci, che siano effettivamente implementati. Progetti di lungo termine, altrimenti c&#8217;\u00e8 il rischio che, finito il progetto, finisca tutto l\u00ec e le cose ritornino come prima. Io sto nel board dell\u2019<strong>Adaptation Fund delle Nazioni Unite<\/strong> che finanzia progetti medio-piccoli, quindi con un budget di una decina di milioni dollari, erogando direttamente alle agenzie dei Paesi che implementano i progetti. L\u2019elemento importante \u00e8 il processo di monitoraggio internazionale dell&#8217;esecuzione e il <em>follow up<\/em> con cui si accerta che questi progetti entrino nel tessuto del Paese stesso. La verifica ex-post \u00e8 fondamentale. Bisogna poi resistere alla tentazione di fare progetti esageratamente sbilanciati rispetto alla capacit\u00e0 gestionale e di assorbimento. <strong>Dobbiamo evitare di costruire cattedrali nel deserto<\/strong>, letteralmente.<\/p>\n<p><strong>Quale \u00e8 il settore da attenzionare per l\u2019adattamento nei Paesi della costa meridionale del Mediterraneo, come Libia, Algeria, Egitto? <\/strong><\/p>\n<p>L&#8217;acqua \u00e8 il problema numero uno. Questo perch\u00e9 in situazioni dove gi\u00e0 la risorsa idrica \u00e8 critica, un eventuale piccolo spostamento della risorsa pu\u00f2 avere effetti completamente sproporzionati rispetto all&#8217;effettivo riduzione. L&#8217;altro rischio che bisogna evitare \u00e8 trovare soluzioni che poi rischiano di avere degli effetti negativi sul pianeta in generale. <strong>Se l&#8217;acqua manca non possiamo risolverlo con impianti di desalinizzazione bruciando combustibili fossili<\/strong>. Serve una visione sistemica intelligente e innovativa.<\/p>\n<div style=\"box-shadow: 10px 10px 28px 0px rgba(171,171,171,1); padding: 25px;\">Biografia<br \/>\n<strong>Emanuele Bompan<\/strong><br \/>\n<a href=\"http:\/\/www.emanuelebompan.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Giornalista ambientale<\/a> e geografo. Si occupa di economia circolare, cambiamenti climatici, green-economy, politica americana. E&#8217; Direttore della rivista <a href=\"http:\/\/materiarinnovabile.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Materia Rinnovabile<\/a>, collabora con testate come La Stampa, Nuova Ecologia e Oltremare. Ha scritto <a href=\"https:\/\/www.hoepli.it\/libro\/atlante-geopolitico-dell-acqua\/9788820390433.html\" target=\"_blank\" rel=\"noopener noreferrer\">l&#8217;Atlante geopolitico dell&#8217;Acqua<\/a> (2019),<a href=\"https:\/\/www.amazon.it\/grabbing-Guerre-nascoste-lacqua-secolo\/dp\/8830724025\" target=\"_blank\" rel=\"noopener noreferrer\">Water Grabbing &#8211; le guerre nascoste per l&#8217;acqua nel XXI secolo<\/a> (2018) &#8220;<a href=\"http:\/\/www.libreriauniversitaria.it\/cosa-economia-circolare-bompan-emanuele\/libro\/9788866271864\" target=\"_blank\" rel=\"noopener noreferrer\">Che cosa \u00e8 l&#8217;economia circolare<\/a>&#8221; (2017). Ha vinto per quattro volte l\u2019European Journalism Center IDR Grant, una volta la Middlebury Environmental Journalism Fellowship, una volta la Google DNI Initiative ed \u00e8 stato nominato Giornalista per la Terra nel 2015.<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2020\/04\/bompan-bio.png\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante la conferenza Mare Climaticum Nostrum, il climatologo del Centro Euro-Mediterraneo sui Cambiamenti climatici ha presentato a Oltremare un quadro completo e accurato di una regione particolarmente esposta. Riscaldamento dei mari, siccit\u00e0, impatti sulla salute e sulla crescita economica i [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":15982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[165],"tags":[239,1147,1148,1140,1149],"class_list":["post-15953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviste","tag-clima","tag-cmcc","tag-mari","tag-mediterraneo","tag-riscaldamento-globale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc) - Oltremare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc) - Oltremare\" \/>\n<meta property=\"og:description\" content=\"Durante la conferenza Mare Climaticum Nostrum, il climatologo del Centro Euro-Mediterraneo sui Cambiamenti climatici ha presentato a Oltremare un quadro completo e accurato di una regione particolarmente esposta. Riscaldamento dei mari, siccit\u00e0, impatti sulla salute e sulla crescita economica i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/\" \/>\n<meta property=\"og:site_name\" content=\"Oltremare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-03T13:53:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T16:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2022\/10\/MareClimaticum2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emanuele Bompan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aics_it\" \/>\n<meta name=\"twitter:site\" content=\"@aics_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emanuele Bompan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/\"},\"author\":{\"name\":\"Emanuele Bompan\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/person\\\/7d9a8d1a87b6775f532e5b3e76d52c75\"},\"headline\":\"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc)\",\"datePublished\":\"2022-10-03T13:53:48+00:00\",\"dateModified\":\"2022-10-06T16:01:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/\"},\"wordCount\":1267,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MareClimaticum2.jpeg\",\"keywords\":[\"Clima\",\"Cmcc\",\"mari\",\"Mediterraneo\",\"riscaldamento globale\"],\"articleSection\":[\"Interviste\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/\",\"name\":\"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc) - Oltremare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MareClimaticum2.jpeg\",\"datePublished\":\"2022-10-03T13:53:48+00:00\",\"dateModified\":\"2022-10-06T16:01:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MareClimaticum2.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/MareClimaticum2.jpeg\",\"width\":1600,\"height\":900,\"caption\":\"Mare Climaticum Nostrum\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/interviste\\\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"name\":\"Oltremare\",\"description\":\"Il Blog della cooperazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\",\"name\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"width\":300,\"height\":74,\"caption\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\\\/\",\"https:\\\/\\\/x.com\\\/aics_it\",\"https:\\\/\\\/www.instagram.com\\\/aics_cooperazione_it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbssygnjreKD1Se1mDeCQ5w\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/person\\\/7d9a8d1a87b6775f532e5b3e76d52c75\",\"name\":\"Emanuele Bompan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bompan.png\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bompan.png\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bompan.png\",\"caption\":\"Emanuele Bompan\"},\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/author\\\/emanuelebompan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc) - Oltremare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/","og_locale":"it_IT","og_type":"article","og_title":"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc) - Oltremare","og_description":"Durante la conferenza Mare Climaticum Nostrum, il climatologo del Centro Euro-Mediterraneo sui Cambiamenti climatici ha presentato a Oltremare un quadro completo e accurato di una regione particolarmente esposta. Riscaldamento dei mari, siccit\u00e0, impatti sulla salute e sulla crescita economica i [&hellip;]","og_url":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/","og_site_name":"Oltremare","article_publisher":"https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/","article_published_time":"2022-10-03T13:53:48+00:00","article_modified_time":"2022-10-06T16:01:50+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2022\/10\/MareClimaticum2.jpeg","type":"image\/jpeg"}],"author":"Emanuele Bompan","twitter_card":"summary_large_image","twitter_creator":"@aics_it","twitter_site":"@aics_it","twitter_misc":{"Scritto da":"Emanuele Bompan","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#article","isPartOf":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/"},"author":{"name":"Emanuele Bompan","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/person\/7d9a8d1a87b6775f532e5b3e76d52c75"},"headline":"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc)","datePublished":"2022-10-03T13:53:48+00:00","dateModified":"2022-10-06T16:01:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/"},"wordCount":1267,"commentCount":0,"publisher":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2022\/10\/MareClimaticum2.jpeg","keywords":["Clima","Cmcc","mari","Mediterraneo","riscaldamento globale"],"articleSection":["Interviste"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/","url":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/","name":"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc) - Oltremare","isPartOf":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#primaryimage"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2022\/10\/MareClimaticum2.jpeg","datePublished":"2022-10-03T13:53:48+00:00","dateModified":"2022-10-06T16:01:50+00:00","breadcrumb":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#primaryimage","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2022\/10\/MareClimaticum2.jpeg","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2022\/10\/MareClimaticum2.jpeg","width":1600,"height":900,"caption":"Mare Climaticum Nostrum"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/interviste\/il-mediterraneo-al-centro-dellazione-climatica-intervista-ad-antonio-navarra-cmcc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aics.gov.it\/oltremare\/"},{"@type":"ListItem","position":2,"name":"Il Mediterraneo al centro dell\u2019azione climatica. Intervista ad Antonio Navarra (Cmcc)"}]},{"@type":"WebSite","@id":"https:\/\/www.aics.gov.it\/oltremare\/#website","url":"https:\/\/www.aics.gov.it\/oltremare\/","name":"Oltremare","description":"Il Blog della cooperazione","publisher":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aics.gov.it\/oltremare\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization","name":"Agenzia Italiana per la Cooperazione allo Sviluppo","url":"https:\/\/www.aics.gov.it\/oltremare\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","width":300,"height":74,"caption":"Agenzia Italiana per la Cooperazione allo Sviluppo"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/","https:\/\/x.com\/aics_it","https:\/\/www.instagram.com\/aics_cooperazione_it\/","https:\/\/www.youtube.com\/channel\/UCbssygnjreKD1Se1mDeCQ5w"]},{"@type":"Person","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/person\/7d9a8d1a87b6775f532e5b3e76d52c75","name":"Emanuele Bompan","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/04\/bompan.png","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/04\/bompan.png","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/04\/bompan.png","caption":"Emanuele Bompan"},"url":"https:\/\/www.aics.gov.it\/oltremare\/author\/emanuelebompan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/15953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/comments?post=15953"}],"version-history":[{"count":9,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/15953\/revisions"}],"predecessor-version":[{"id":15985,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/15953\/revisions\/15985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/media\/15982"}],"wp:attachment":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/media?parent=15953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/categories?post=15953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/tags?post=15953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}