{"id":18928,"date":"2026-07-15T11:34:59","date_gmt":"2026-07-15T09:34:59","guid":{"rendered":"https:\/\/www.aics.gov.it\/oltremare\/?p=18928"},"modified":"2026-07-15T11:34:59","modified_gmt":"2026-07-15T09:34:59","slug":"a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale","status":"publish","type":"post","link":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/","title":{"rendered":"A Malindi da 20 Paesi dell&#8217;Africa. La cooperazione \u00e8 spaziale"},"content":{"rendered":"<p><em>Dall\u2019assemblaggio dei cubesat, satelliti miniaturizzati utili anche a monitorare i cambiamenti climatici, fino alle nuove frontiere del diritto. Specializzazioni al centro dei nuovi corsi di formazione al Centro Luigi Broglio, spiega Teodoro Valente, presidente dell\u2019Agenzia spaziale italiana<\/em><!--more--><\/p>\n<p>Giovani italiani alla scoperta di un\u2019altra <strong>Malindi<\/strong>. Studenti e non turisti, che alle acque turchesi e alla barriera corallina della costa keniana sull&#8217;Oceano Indiano, \u201cbuen retiro\u201d per una comunit\u00e0 italiana di circa 3mila persone, hanno preferito il <strong>Centro spaziale Luigi Broglio<\/strong>, con le sirene che segnalano il ruotare delle antenne.<\/p>\n<p>Un\u2019eccellenza italiana, nata proprio qui grazie alla vicinanza all\u2019equatore e da subito proiettata nel futuro, gi\u00e0 negli anni Sessanta del secolo scorso e ancora oggi, <strong>al tempo del Piano Mattei per l\u2019Africa<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-18930 alignleft\" src=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-un-giorno-al-Centro-spaziale-Luigi-Broglio-600x450.jpeg\" alt=\"\" width=\"376\" height=\"282\" srcset=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-un-giorno-al-Centro-spaziale-Luigi-Broglio-600x450.jpeg 600w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-un-giorno-al-Centro-spaziale-Luigi-Broglio-1024x768.jpeg 1024w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-un-giorno-al-Centro-spaziale-Luigi-Broglio-768x576.jpeg 768w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-un-giorno-al-Centro-spaziale-Luigi-Broglio.jpeg 1280w\" sizes=\"auto, (max-width: 376px) 100vw, 376px\" \/>Ed \u00e8 forse un segno che oggi, in una mattinata illuminata dal sole, dall\u2019Italia non arrivino turisti, ma studenti. Sono vincitori di borse offerte dal <strong>Lumsa University Africa Center (Luac)<\/strong>, un progetto ideato dall\u2019<strong>ambasciatore Pietro Sebastiani<\/strong>, membro del consiglio di amministrazione dell\u2019ateneo romano: l\u2019obiettivo \u00e8 favorire <strong>una conoscenza del continente al di l\u00e0 di stereotipi spesso penalizzanti<\/strong>.<\/p>\n<p>\u00c8 il posto giusto, Malindi, ex villaggio di pescatori divenuto paradiso turistico. La popolarit\u00e0 del luogo non \u00e8 cominciata con il <em>Billionaire<\/em>, il resort fronte mare di Flavio Briatore, ma grazie a quella che all\u2019epoca si chiamava Base San Marco e oggi \u00e8 il Centro spaziale Luigi Broglio. <strong>Furono infatti i suoi ingegneri a far girare il passaparola sulla bellezza della zona<\/strong>.<\/p>\n<p>Oggi <strong>la struttura \u00e8 gestita dall\u2019Agenzia spaziale italiana (Asi) e dall\u2019Agenzia spaziale keniana (Ksa)<\/strong>. Ad accoglierli, gli studenti della Lumsa hanno trovato personale keniano che giorno e notte sorveglia la struttura. Non c\u2019\u00e8 da stupirsi: siamo a quasi un\u2019ora di automobile da Malindi, lungo la direttrice che porta alla frontiera con la Somalia, una zona caldissima dell\u2019Africa, che negli anni ha conosciuto restrizioni e particolari misure di sicurezza. Nonostante un cuoco che serve fettuccine al rag\u00f9, il Centro non \u00e8 insomma un paradiso per turisti, pur occupandosi di cieli: <strong>riceve dati satellitari e di telemetria cruciali per l\u2019osservazione della Terra e dell\u2019universo<\/strong>, condivisi poi con le agenzie spaziali di mezzo mondo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-18932 alignright\" src=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-gli-studenti-del-Luac-di-fronte-a-plance-di-comando-anni-Sessanta-nel-museo-allestito-allinterno-del-Centro-spaziale-Luigi-Broglio-600x338.jpg\" alt=\"\" width=\"433\" height=\"244\" srcset=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-gli-studenti-del-Luac-di-fronte-a-plance-di-comando-anni-Sessanta-nel-museo-allestito-allinterno-del-Centro-spaziale-Luigi-Broglio-600x338.jpg 600w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-gli-studenti-del-Luac-di-fronte-a-plance-di-comando-anni-Sessanta-nel-museo-allestito-allinterno-del-Centro-spaziale-Luigi-Broglio-1024x576.jpg 1024w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-gli-studenti-del-Luac-di-fronte-a-plance-di-comando-anni-Sessanta-nel-museo-allestito-allinterno-del-Centro-spaziale-Luigi-Broglio-768x432.jpg 768w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-gli-studenti-del-Luac-di-fronte-a-plance-di-comando-anni-Sessanta-nel-museo-allestito-allinterno-del-Centro-spaziale-Luigi-Broglio.jpg 1280w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/>A rispondere alle domande dei giovani \u00e8 il <strong>professor Giancarlo Santilli<\/strong>, responsabile del Centro. \u201c<em>Nacque sotto la gestione dell\u2019universit\u00e0 La Sapienza di Roma<\/em>\u201d, spiega. \u201c<em>La sua storia \u00e8 legata a Luigi Broglio, generale dell\u2019aeronautica originario di Mestre, professore e pioniere: fu lui a scegliere il sito, che per la vicinanza all\u2019equatore era ideale per il lancio di satelliti nello spazio<\/em>\u201d. Allo scienziato, scomparso nel 2001, \u00e8 dedicato un museo. Qui si pu\u00f2 visitare la sala di controllo utilizzata per la prima volta nel 1967: grazie a una collaborazione con la Nasa, l\u2019Italia era gi\u00e0 divenuta il terzo Paese al mondo a lanciare autonomamente un satellite in orbita dopo Stati Uniti e Urss. Enrico Mattei era morto da alcuni anni. Era stato per\u00f2 proprio lui, con la sua Eni, a donare a Broglio la piattaforma petrolifera Santa Rita, la santa delle cose impossibili: come quei lanci che si ripeterono senza errori proprio qui di fronte, dal \u201csegmento marino\u201d della Base. Oggi, oltre il museo, superata una cappella dove il professore era solito pregare davanti a un crocifisso illuminato dai riflessi del mare, c\u2019\u00e8 un cantiere. Per avere dettagli e un quadro d\u2019insieme chiediamo al <strong>professor Teodoro Valente, il presidente di Asi<\/strong>. \u201c<em>\u00c8 in costruzione<\/em>\u201d, spiega, \u201c<em>un polo multifunzionale della nostra Scuola internazionale in discipline spaziali, un\u2019iniziativa condivisa con l\u2019Agenzia spaziale keniana e gi\u00e0 lanciata durante una visita al Centro del presidente della Repubblica Sergio Mattarella nel 2023<\/em>\u201d. Saranno realizzati laboratori pi\u00f9 grandi e attrezzati, che accoglieranno giovani provenienti non solo dal Kenya, ma da una ventina di Paesi dell\u2019Africa. \u201c<em>Il primo corso, in diritto spaziale, organizzato con l\u2019Ufficio delle Nazioni Unite Unoosa, partir\u00e0 a fine anno<\/em>\u201d, annuncia Valente. \u201c<em>Ci sar\u00e0 un\u2019offerta ampia, per rispondere alle richieste dei Paesi del continente<\/em>\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-18931 alignleft\" src=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-a-lezione-di-cubesat-600x338.jpg\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-a-lezione-di-cubesat-600x338.jpg 600w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-a-lezione-di-cubesat-1024x576.jpg 1024w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-a-lezione-di-cubesat-768x432.jpg 768w, https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-a-lezione-di-cubesat.jpg 1280w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/>L\u2019obiettivo \u00e8 fare del Centro <strong>un hub di formazione<\/strong>. Un grande progetto fatto anche di piccoli cubi. Si chiamano cubesat e sono satelliti miniaturizzati di dieci centimetri per lato. Leggeri e resistenti, sono dotati di pannelli solari e computer di bordo. \u201c<em>Un sistema low-cost per portare in orbita piccoli payload scientifici<\/em>\u201d, sintetizza Valente. \u201c<em>Permettono di raccogliere dati utilizzati anche per il monitoraggio agricolo e dei cambiamenti climatici o nella gestione dei disastri naturali<\/em>\u201d. I corsi di cubesat saranno un punto di forza, con assemblaggio e test in aula su vibrazioni e carichi.<\/p>\n<p>Si torna al Piano Mattei, nello spirito di Broglio. \u201c<em>I Paesi africani non saranno solo destinatari dei corsi, ma attori coinvolti appieno<\/em>\u201d, sottolinea Valente. \u201c<em>Potranno contribuire con esperti, infrastrutture e competenze, per una partnership totale<\/em>\u201d.<\/p>\n<div style=\"box-shadow: 10px 10px 28px 0px rgba(171,171,171,1); padding: 25px;\"><span style=\"color: #000000;\">Biografia<\/span><br \/>\n<span style=\"color: #000000;\"><strong>Vincenzo Giardina<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Laureato in storia contemporanea, \u00e8 giornalista professionista. Coordina il notiziario Esteri dell\u2019agenzia di stampa Dire e firma per quotidiani e settimanali, tra cui Il Venerd\u00ec di Repubblica, Internazionale, L\u2019Espresso, Huffington Post, L&#8217;Osservatore Romano e altri media vaticani. Dopo aver lavorato per l\u2019agenzia di stampa missionaria Misna si \u00e8 specializzato su Africa, diritti umani, cooperazione internazionale e lotta contro le disuguaglianze. Ha viaggiato molto: dalla Bolivia al Nepal passando per Ucraina, Sahel e Corno d\u2019Africa, anche in contesti segnati da conflitti, fragilit\u00e0 o svantaggio sociale. Collabora con AICS scrivendo sul magazine Oltremare ed \u00e8 ospite di Radio Rai ed altre emittenti, italiane e vaticane. Coordina corsi di formazione del Parlamento europeo rivolti a giornalisti, \u00e8 relatore e moderatore di conferenze, e parla anche russo.<\/span><br \/>\n<a href=\"https:\/\/www.vincenzogiardina.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.vincenzogiardina.org<\/a><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2020\/04\/giardina-bio.png\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dall\u2019assemblaggio dei cubesat, satelliti miniaturizzati utili anche a monitorare i cambiamenti climatici, fino alle nuove frontiere del diritto. Specializzazioni al centro dei nuovi corsi di formazione al Centro Luigi Broglio, spiega Teodoro Valente, presidente dell\u2019Agenzia spaziale italiana<\/p>\n","protected":false},"author":36,"featured_media":18929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[1579,1578,337,1476],"class_list":["post-18928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prosperita","tag-asi","tag-cooperazione-spaziale","tag-kenya","tag-piano-mattei"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Malindi da 20 Paesi dell&#039;Africa. La cooperazione \u00e8 spaziale - Oltremare<\/title>\n<meta name=\"description\" content=\"\u00c8 in costruzione un polo multifunzionale della Scuola internazionale in discipline spaziali, un\u2019iniziativa condivisa con l\u2019Agenzia spaziale keniana e gi\u00e0 lanciata durante una visita al Centro del presidente della Repubblica Sergio Mattarella nel 2023\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Malindi da 20 Paesi dell&#039;Africa. La cooperazione \u00e8 spaziale - Oltremare\" \/>\n<meta property=\"og:description\" content=\"\u00c8 in costruzione un polo multifunzionale della Scuola internazionale in discipline spaziali, un\u2019iniziativa condivisa con l\u2019Agenzia spaziale keniana e gi\u00e0 lanciata durante una visita al Centro del presidente della Repubblica Sergio Mattarella nel 2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/\" \/>\n<meta property=\"og:site_name\" content=\"Oltremare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T09:34:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giorgio Bartolomucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aics_it\" \/>\n<meta name=\"twitter:site\" content=\"@aics_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vincenzo Giardina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/\"},\"author\":{\"name\":\"Giorgio Bartolomucci\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/person\\\/366926f64550e01f22be287462a02414\"},\"headline\":\"A Malindi da 20 Paesi dell&#8217;Africa. La cooperazione \u00e8 spaziale\",\"datePublished\":\"2026-07-15T09:34:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/\"},\"wordCount\":918,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg\",\"keywords\":[\"ASI\",\"Cooperazione spaziale\",\"Kenya\",\"Piano Mattei\"],\"articleSection\":[\"Prosperit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/\",\"name\":\"A Malindi da 20 Paesi dell'Africa. La cooperazione \u00e8 spaziale - Oltremare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg\",\"datePublished\":\"2026-07-15T09:34:59+00:00\",\"description\":\"\u00c8 in costruzione un polo multifunzionale della Scuola internazionale in discipline spaziali, un\u2019iniziativa condivisa con l\u2019Agenzia spaziale keniana e gi\u00e0 lanciata durante una visita al Centro del presidente della Repubblica Sergio Mattarella nel 2023\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/articoli\\\/prosperita\\\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Malindi da 20 Paesi dell&#8217;Africa. La cooperazione \u00e8 spaziale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"name\":\"Oltremare\",\"description\":\"Il Blog della cooperazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\",\"name\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"width\":300,\"height\":74,\"caption\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\\\/\",\"https:\\\/\\\/x.com\\\/aics_it\",\"https:\\\/\\\/www.instagram.com\\\/aics_cooperazione_it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbssygnjreKD1Se1mDeCQ5w\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/person\\\/366926f64550e01f22be287462a02414\",\"name\":\"Giorgio Bartolomucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ce9ac0d7ddef332f6be800f5fa59bedce6e5d6f6f7bafb322f31ace0e15532b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ce9ac0d7ddef332f6be800f5fa59bedce6e5d6f6f7bafb322f31ace0e15532b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ce9ac0d7ddef332f6be800f5fa59bedce6e5d6f6f7bafb322f31ace0e15532b?s=96&d=mm&r=g\",\"caption\":\"Giorgio Bartolomucci\"},\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Malindi da 20 Paesi dell'Africa. La cooperazione \u00e8 spaziale - Oltremare","description":"\u00c8 in costruzione un polo multifunzionale della Scuola internazionale in discipline spaziali, un\u2019iniziativa condivisa con l\u2019Agenzia spaziale keniana e gi\u00e0 lanciata durante una visita al Centro del presidente della Repubblica Sergio Mattarella nel 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/","og_locale":"it_IT","og_type":"article","og_title":"A Malindi da 20 Paesi dell'Africa. La cooperazione \u00e8 spaziale - Oltremare","og_description":"\u00c8 in costruzione un polo multifunzionale della Scuola internazionale in discipline spaziali, un\u2019iniziativa condivisa con l\u2019Agenzia spaziale keniana e gi\u00e0 lanciata durante una visita al Centro del presidente della Repubblica Sergio Mattarella nel 2023","og_url":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/","og_site_name":"Oltremare","article_publisher":"https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/","article_published_time":"2026-07-15T09:34:59+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg","type":"image\/jpeg"}],"author":"Giorgio Bartolomucci","twitter_card":"summary_large_image","twitter_creator":"@aics_it","twitter_site":"@aics_it","twitter_misc":{"Scritto da":"Vincenzo Giardina","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/#article","isPartOf":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/"},"author":{"name":"Giorgio Bartolomucci","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/person\/366926f64550e01f22be287462a02414"},"headline":"A Malindi da 20 Paesi dell&#8217;Africa. La cooperazione \u00e8 spaziale","datePublished":"2026-07-15T09:34:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/"},"wordCount":918,"publisher":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg","keywords":["ASI","Cooperazione spaziale","Kenya","Piano Mattei"],"articleSection":["Prosperit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/","url":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/","name":"A Malindi da 20 Paesi dell'Africa. La cooperazione \u00e8 spaziale - Oltremare","isPartOf":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/#primaryimage"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg","datePublished":"2026-07-15T09:34:59+00:00","description":"\u00c8 in costruzione un polo multifunzionale della Scuola internazionale in discipline spaziali, un\u2019iniziativa condivisa con l\u2019Agenzia spaziale keniana e gi\u00e0 lanciata durante una visita al Centro del presidente della Repubblica Sergio Mattarella nel 2023","breadcrumb":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/#primaryimage","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2026\/07\/Malindi-il-Centro-spaziale-Luigi-Broglio-al-tramonto.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.aics.gov.it\/oltremare\/articoli\/prosperita\/a-malindi-da-20-paesi-dellafrica-la-cooperazione-e-spaziale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aics.gov.it\/oltremare\/"},{"@type":"ListItem","position":2,"name":"A Malindi da 20 Paesi dell&#8217;Africa. La cooperazione \u00e8 spaziale"}]},{"@type":"WebSite","@id":"https:\/\/www.aics.gov.it\/oltremare\/#website","url":"https:\/\/www.aics.gov.it\/oltremare\/","name":"Oltremare","description":"Il Blog della cooperazione","publisher":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aics.gov.it\/oltremare\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization","name":"Agenzia Italiana per la Cooperazione allo Sviluppo","url":"https:\/\/www.aics.gov.it\/oltremare\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","width":300,"height":74,"caption":"Agenzia Italiana per la Cooperazione allo Sviluppo"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/","https:\/\/x.com\/aics_it","https:\/\/www.instagram.com\/aics_cooperazione_it\/","https:\/\/www.youtube.com\/channel\/UCbssygnjreKD1Se1mDeCQ5w"]},{"@type":"Person","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/person\/366926f64550e01f22be287462a02414","name":"Giorgio Bartolomucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8ce9ac0d7ddef332f6be800f5fa59bedce6e5d6f6f7bafb322f31ace0e15532b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ce9ac0d7ddef332f6be800f5fa59bedce6e5d6f6f7bafb322f31ace0e15532b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ce9ac0d7ddef332f6be800f5fa59bedce6e5d6f6f7bafb322f31ace0e15532b?s=96&d=mm&r=g","caption":"Giorgio Bartolomucci"},"url":""}]}},"_links":{"self":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/18928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/comments?post=18928"}],"version-history":[{"count":1,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/18928\/revisions"}],"predecessor-version":[{"id":18933,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/18928\/revisions\/18933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/media\/18929"}],"wp:attachment":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/media?parent=18928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/categories?post=18928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/tags?post=18928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}