{"id":9561,"date":"2019-12-18T11:15:44","date_gmt":"2019-12-18T10:15:44","guid":{"rendered":"https:\/\/www.aics.gov.it\/oltremare\/?p=9561"},"modified":"2019-12-20T12:18:34","modified_gmt":"2019-12-20T11:18:34","slug":"cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione","status":"publish","type":"post","link":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/","title":{"rendered":"Cooperazione. Summit Diaspore ricomincia da tre: &#8216;ora fase nuova&#8217; la terza edizione a Roma, con anche un focus sull&#8217;informazione"},"content":{"rendered":"<p>&#8220;Non so cosa sara&#8217; domani ma sono felice&#8221; dice Cleophas Adrien Dioma, il coordinatore del Summit nazionale delle diaspore. Sono trascorsi tre anni dall&#8217;avvio del progetto e l&#8217;ultima edizione, a Roma, al Centro congressi della Pontificia universit\u00e0 Tommaso d&#8217;Aquino, \u00e8 allo stesso tempo occasione per tirare le somme e guardare al futuro.<\/p>\n<p>&#8220;Bilancio positivo&#8221; risponde all&#8217;agenzia DIRE Luca Maestripieri, direttore dell&#8217;Agenzia italiana per la cooperazione allo sviluppo (Aics), sostenitrice chiave del Summit insieme con Fondazione Charlemagne e Fondazioni for Africa. La prospettiva resta favorire la partecipazione delle comunit\u00e0 con esperienza migratoria ai progetti per la crescita dei loro Paesi d&#8217;origine.<br \/>\nNel corso dei tre anni, segnati in Italia dalla riforma della cooperazione che indica nelle &#8220;diaspore&#8221; un interlocutore fondamentale, sono per\u00f2 stati esplorati limiti e tentate strade nuove. Di questo, guardando alle &#8220;prossime edizioni&#8221; del Summit, parla ancora Maestripieri: &#8220;L&#8217;incontro del mondo delle comunit\u00e0 delle diaspore con il settore privato, non solo non profit ma anche profit, \u00e8 uno dei percorsi da immaginare nell&#8217;immediato futuro&#8221;.<\/p>\n<p>Il bilancio dell&#8217;impegno di aggregazione gi\u00e0 assolto, con decine di incontri che hanno coinvolto oltre 300 associazioni in tutta Italia e l&#8217;attenzione particolare per le imprese gestite da migranti, si intreccia dunque alla riflessione sul futuro.<br \/>\n&#8220;Abbiamo lavorato al fianco delle comunit\u00e0 per farle crescere e per permettergli di approfondire le proprie competenze&#8221; sottolinea Dioma, convinto che il percorso sia &#8220;lungo&#8221; e gli obiettivi &#8220;altissimi&#8221;.<br \/>\nAlla Tommaso d&#8217;Aquino la parola se la prendono soprattutto le diaspore, con le loro associazioni. Ecco Abdullahi Ahmed, presidente di Generazione Ponte: per rafforzare la cooperazione allo sviluppo suggerisce di riprendere in mano il Manifesto di Ventotene, &#8220;un esempio di dialogo che ha permesso di ricostruire l&#8217;Europa sulla pace&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9563\" src=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2019\/12\/cid_image001_png@01D5B4DF.png\" alt=\"\" width=\"583\" height=\"310\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Lo sguardo \u00e8 anche alla sua Somalia, Paese natale ancora segnato da violenze, riferimento importante per la politica internazionale dell&#8217;Italia, solo uno tra tanti per il Summit. In un video-messaggio parla di diaspore a 360 gradi la vice-ministra degli Esteri, Emanuela Del Re. La sua base di partenza \u00e8 che le rimesse inviate dai migranti nei loro Paesi d&#8217;origine hanno un ruolo chiave in una prospettiva di sviluppo. E poi c&#8217;\u00e8 l&#8217;investimento che viene fatto qui in Italia: &#8220;Solo la comunit\u00e0 albanese &#8211; calcola Del Re &#8211; \u00e8 titolare di 30mila imprese&#8221;.<br \/>\nDalla terza edizione del Summit, chiusura di una prima fase del progetto centrata su mappatura, aggregazione e coinvolgimento delle associazioni, emerge pi\u00f9 di un appello. &#8220;Non si pu\u00f2 essere stranieri per sempre, bisogna poter essere cittadini attivi e partecipare appieno della vita sociale&#8221; dicono nell&#8217;emiciclo del Centro congressi.<br \/>\nDel rapporto tra l&#8217;Italia e il mondo e di frontiere sempre pi\u00f9 impalpabili si parla poi in un panel sull'&#8221;informazione che cambia&#8221; e le &#8220;notizie dell&#8217;Italia plurale&#8221;. La riflessione \u00e8 anticipata dallo scrittore italo-senegalese Pap Khouma, che da\u2019 l&#8217;interculturalit\u00e0 come dato di fatto. &#8220;Le verit\u00e0 sono tre&#8221; dice: &#8220;La mia, la tua e la verit\u00e0&#8221;. Miruna Cajvaneanu, cronista di origini rumene, denuncia &#8220;storture&#8221; e &#8220;narrazioni sempre negative&#8221; sulle migrazioni. Un punto evidenziato anche dallo scrittore Tahar Lamri, arrivato in Italia dall&#8217;Algeria nel 1986, secondo il quale &#8220;gli insulti restano e a cambiare \u00e8 solo la natura del razzismo&#8221;. Anna Meli, dell&#8217;associazione Carta di Roma, chiede di aprirsi al mondo cominciando dai tg, &#8220;che hanno un numero di notizie sugli altri Paesi molto basso&#8221;.<\/p>\n<p>Secondo Vincenzo Giardina, della Dire, organizzatrice quest&#8217;anno insieme con il Summit di una serie di incontri con la &#8220;stampa multiculturale&#8221;, nelle redazioni dovrebbe trovare posto anche chi ha altre radici. &#8220;Colleghi che con il loro talento e la loro professionalit\u00e0 &#8211; dice il giornalista \u2013 aggiungerebbero prospettive e consentirebbero di raccontare meglio l&#8217;Italia e il mondo&#8221;.<\/p>\n<p>Gli appelli a coinvolgere le associazioni nel sistema della cooperazione &#8211; &#8220;Vogliamo che prendano soldi e partecipino ai progetti, diventando ponte tra l&#8217;Italia e i Paesi di origine&#8221; dice Emilio Ciarlo, responsabile comunicazione di Aics \u2013 si intrecciano ai racconti di vita e difficolt\u00e0 quotidiane. Strappa un sorriso Ahmad Ejaz, giornalista nato in Pakistan da oltre 20 anni in Italia: &#8220;Una volta una mia vicina, saputo che venivo dal Pakistan, mi disse: &#8216;Bene, anche la mia filippina viene dalla Somalia&#8217;\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Non so cosa sara&#8217; domani ma sono felice&#8221; dice Cleophas Adrien Dioma, il coordinatore del Summit nazionale delle diaspore. Sono trascorsi tre anni dall&#8217;avvio del progetto e l&#8217;ultima edizione, a Roma, al Centro congressi della Pontificia universit\u00e0 Tommaso d&#8217;Aquino, \u00e8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[186],"tags":[],"class_list":["post-9561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cooperazione. Summit Diaspore ricomincia da tre: &#039;ora fase nuova&#039; la terza edizione a Roma, con anche un focus sull&#039;informazione - Oltremare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cooperazione. Summit Diaspore ricomincia da tre: &#039;ora fase nuova&#039; la terza edizione a Roma, con anche un focus sull&#039;informazione - Oltremare\" \/>\n<meta property=\"og:description\" content=\"&#8220;Non so cosa sara&#8217; domani ma sono felice&#8221; dice Cleophas Adrien Dioma, il coordinatore del Summit nazionale delle diaspore. Sono trascorsi tre anni dall&#8217;avvio del progetto e l&#8217;ultima edizione, a Roma, al Centro congressi della Pontificia universit\u00e0 Tommaso d&#8217;Aquino, \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Oltremare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-18T10:15:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-20T11:18:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Oltremare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aics_it\" \/>\n<meta name=\"twitter:site\" content=\"@aics_it\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oltremare\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/\"},\"author\":{\"name\":\"Oltremare\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/person\\\/839e251090f440ea6a1f960a5050e424\"},\"headline\":\"Cooperazione. Summit Diaspore ricomincia da tre: &#8216;ora fase nuova&#8217; la terza edizione a Roma, con anche un focus sull&#8217;informazione\",\"datePublished\":\"2019-12-18T10:15:44+00:00\",\"dateModified\":\"2019-12-20T11:18:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/\"},\"wordCount\":712,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/\",\"name\":\"Cooperazione. Summit Diaspore ricomincia da tre: 'ora fase nuova' la terza edizione a Roma, con anche un focus sull'informazione - Oltremare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg\",\"datePublished\":\"2019-12-18T10:15:44+00:00\",\"dateModified\":\"2019-12-20T11:18:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg\",\"width\":1440,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/rubriche\\\/eventi\\\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cooperazione. Summit Diaspore ricomincia da tre: &#8216;ora fase nuova&#8217; la terza edizione a Roma, con anche un focus sull&#8217;informazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"name\":\"Oltremare\",\"description\":\"Il Blog della cooperazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\",\"name\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"width\":300,\"height\":74,\"caption\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\\\/\",\"https:\\\/\\\/x.com\\\/aics_it\",\"https:\\\/\\\/www.instagram.com\\\/aics_cooperazione_it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbssygnjreKD1Se1mDeCQ5w\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/person\\\/839e251090f440ea6a1f960a5050e424\",\"name\":\"Oltremare\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5bdd54efc610ff3db8c53755c1599daf68165eb144e678103c1ac46fb81fe6a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5bdd54efc610ff3db8c53755c1599daf68165eb144e678103c1ac46fb81fe6a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5bdd54efc610ff3db8c53755c1599daf68165eb144e678103c1ac46fb81fe6a0?s=96&d=mm&r=g\",\"caption\":\"Oltremare\"},\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/author\\\/mirus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cooperazione. Summit Diaspore ricomincia da tre: 'ora fase nuova' la terza edizione a Roma, con anche un focus sull'informazione - Oltremare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/","og_locale":"it_IT","og_type":"article","og_title":"Cooperazione. Summit Diaspore ricomincia da tre: 'ora fase nuova' la terza edizione a Roma, con anche un focus sull'informazione - Oltremare","og_description":"&#8220;Non so cosa sara&#8217; domani ma sono felice&#8221; dice Cleophas Adrien Dioma, il coordinatore del Summit nazionale delle diaspore. Sono trascorsi tre anni dall&#8217;avvio del progetto e l&#8217;ultima edizione, a Roma, al Centro congressi della Pontificia universit\u00e0 Tommaso d&#8217;Aquino, \u00e8 [&hellip;]","og_url":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/","og_site_name":"Oltremare","article_publisher":"https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/","article_published_time":"2019-12-18T10:15:44+00:00","article_modified_time":"2019-12-20T11:18:34+00:00","og_image":[{"width":1440,"height":1080,"url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg","type":"image\/jpeg"}],"author":"Oltremare","twitter_card":"summary_large_image","twitter_creator":"@aics_it","twitter_site":"@aics_it","twitter_misc":{"Scritto da":"Oltremare","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#article","isPartOf":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/"},"author":{"name":"Oltremare","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/person\/839e251090f440ea6a1f960a5050e424"},"headline":"Cooperazione. Summit Diaspore ricomincia da tre: &#8216;ora fase nuova&#8217; la terza edizione a Roma, con anche un focus sull&#8217;informazione","datePublished":"2019-12-18T10:15:44+00:00","dateModified":"2019-12-20T11:18:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/"},"wordCount":712,"commentCount":0,"publisher":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/","url":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/","name":"Cooperazione. Summit Diaspore ricomincia da tre: 'ora fase nuova' la terza edizione a Roma, con anche un focus sull'informazione - Oltremare","isPartOf":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#primaryimage"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg","datePublished":"2019-12-18T10:15:44+00:00","dateModified":"2019-12-20T11:18:34+00:00","breadcrumb":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#primaryimage","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-14-at-18.52.57.jpeg","width":1440,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.aics.gov.it\/oltremare\/rubriche\/eventi\/cooperazione-summit-diaspore-ricomincia-da-tre-ora-fase-nuova-la-terza-edizione-a-roma-con-anche-un-focus-sullinformazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aics.gov.it\/oltremare\/"},{"@type":"ListItem","position":2,"name":"Cooperazione. Summit Diaspore ricomincia da tre: &#8216;ora fase nuova&#8217; la terza edizione a Roma, con anche un focus sull&#8217;informazione"}]},{"@type":"WebSite","@id":"https:\/\/www.aics.gov.it\/oltremare\/#website","url":"https:\/\/www.aics.gov.it\/oltremare\/","name":"Oltremare","description":"Il Blog della cooperazione","publisher":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aics.gov.it\/oltremare\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization","name":"Agenzia Italiana per la Cooperazione allo Sviluppo","url":"https:\/\/www.aics.gov.it\/oltremare\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","width":300,"height":74,"caption":"Agenzia Italiana per la Cooperazione allo Sviluppo"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/","https:\/\/x.com\/aics_it","https:\/\/www.instagram.com\/aics_cooperazione_it\/","https:\/\/www.youtube.com\/channel\/UCbssygnjreKD1Se1mDeCQ5w"]},{"@type":"Person","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/person\/839e251090f440ea6a1f960a5050e424","name":"Oltremare","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5bdd54efc610ff3db8c53755c1599daf68165eb144e678103c1ac46fb81fe6a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5bdd54efc610ff3db8c53755c1599daf68165eb144e678103c1ac46fb81fe6a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5bdd54efc610ff3db8c53755c1599daf68165eb144e678103c1ac46fb81fe6a0?s=96&d=mm&r=g","caption":"Oltremare"},"url":"https:\/\/www.aics.gov.it\/oltremare\/author\/mirus\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/9561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/comments?post=9561"}],"version-history":[{"count":4,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/9561\/revisions"}],"predecessor-version":[{"id":9617,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts\/9561\/revisions\/9617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/media\/9562"}],"wp:attachment":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/media?parent=9561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/categories?post=9561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/tags?post=9561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}