{"id":1525,"count":1,"description":"","link":"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/","name":"sistema Italia","slug":"sistema-italia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sistema Italia Archivi - Oltremare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sistema Italia Archivi - Oltremare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Oltremare\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aics_it\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/tag\\\/sistema-italia\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/tag\\\/sistema-italia\\\/\",\"name\":\"sistema Italia Archivi - Oltremare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/tag\\\/sistema-italia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/tag\\\/sistema-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sistema Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#website\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"name\":\"Oltremare\",\"description\":\"Il Blog della cooperazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#organization\",\"name\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/AICS_HEADER_530x130_EC1-e1518178146163.jpg\",\"width\":300,\"height\":74,\"caption\":\"Agenzia Italiana per la Cooperazione allo Sviluppo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aics.gov.it\\\/oltremare\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\\\/\",\"https:\\\/\\\/x.com\\\/aics_it\",\"https:\\\/\\\/www.instagram.com\\\/aics_cooperazione_it\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbssygnjreKD1Se1mDeCQ5w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sistema Italia Archivi - Oltremare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/","og_locale":"it_IT","og_type":"article","og_title":"sistema Italia Archivi - Oltremare","og_url":"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/","og_site_name":"Oltremare","twitter_card":"summary_large_image","twitter_site":"@aics_it","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/","url":"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/","name":"sistema Italia Archivi - Oltremare","isPartOf":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#website"},"breadcrumb":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aics.gov.it\/oltremare\/tag\/sistema-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aics.gov.it\/oltremare\/"},{"@type":"ListItem","position":2,"name":"sistema Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.aics.gov.it\/oltremare\/#website","url":"https:\/\/www.aics.gov.it\/oltremare\/","name":"Oltremare","description":"Il Blog della cooperazione","publisher":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aics.gov.it\/oltremare\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aics.gov.it\/oltremare\/#organization","name":"Agenzia Italiana per la Cooperazione allo Sviluppo","url":"https:\/\/www.aics.gov.it\/oltremare\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/","url":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","contentUrl":"https:\/\/www.aics.gov.it\/oltremare\/wp-content\/uploads\/2018\/02\/AICS_HEADER_530x130_EC1-e1518178146163.jpg","width":300,"height":74,"caption":"Agenzia Italiana per la Cooperazione allo Sviluppo"},"image":{"@id":"https:\/\/www.aics.gov.it\/oltremare\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Agenzia-Italiana-per-la-Cooperazione-allo-Sviluppo-996004880482735\/","https:\/\/x.com\/aics_it","https:\/\/www.instagram.com\/aics_cooperazione_it\/","https:\/\/www.youtube.com\/channel\/UCbssygnjreKD1Se1mDeCQ5w"]}]}},"_links":{"self":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/tags\/1525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.aics.gov.it\/oltremare\/wp-json\/wp\/v2\/posts?tags=1525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}